{"id":7033,"date":"2023-05-08T20:35:00","date_gmt":"2023-05-08T20:35:00","guid":{"rendered":"https:\/\/pinnacleresortspv.com\/?p=7033"},"modified":"2026-03-14T01:22:02","modified_gmt":"2026-03-14T01:22:02","slug":"discovering-erica-maree","status":"publish","type":"post","link":"https:\/\/pinnacleresortspv.com\/es\/blog\/discovering-erica-maree\/","title":{"rendered":"Descubriendo Erica Maree"},"content":{"rendered":"\n<p>Ubicado en el coraz\u00f3n de la Zona Rom\u00e1ntica de Puerto Vallarta, Pinnacle Resorts ofrece a sus hu\u00e9spedes f\u00e1cil acceso a algunas de las mejores tiendas de la zona. Una recomendaci\u00f3n destacada para los viajeros amantes de la moda es visitar la boutique Erica Maree.<\/p>\n\n\n\n<p>La fundadora y dise\u00f1adora Erica Black, originaria de Portland, Oreg\u00f3n y ahora residente de Puerto Vallarta, se inspira en los colores y tradiciones de M\u00e9xico para crear impresionantes prendas y accesorios boho-chic. Viajando por todo M\u00e9xico, colabora con artesanos locales que utilizan t\u00e9cnicas tradicionales transmitidas de generaci\u00f3n en generaci\u00f3n para confeccionar textiles a mano y bordar dise\u00f1os exquisitos.<\/p>\n\n\n\n<p>Comprometida con pr\u00e1cticas de comercio justo, Erica Maree infunde una vibra moderna y playera en estos m\u00e9todos tradicionales de artesan\u00eda, resultando en una colecci\u00f3n \u00fanica y elegante adecuada para salidas a la playa y m\u00e1s all\u00e1. El vibrante mantel de hule, t\u00edpicamente utilizado como cubierta de mesa en M\u00e9xico, se transforma en bolsos de playa, carteras, estuches de cosm\u00e9ticos y fundas para iPad de moda pero funcionales. Cortes contempor\u00e1neos de vestidos y blusas mexicanas tradicionales est\u00e1n adornados con bordados mexicanos, complementados por una adorable l\u00ednea de ropa infantil. Las joyas artesanales muestran el tradicional bordado Huichol y el trabajo en cuero. Erica Maree Home ofrece una variedad de almohadas bordadas, mantas y manteles. No se puede dejar de mencionar los bolsos caracter\u00edsticos, disponibles en dise\u00f1os bordados y opciones de cuero lujoso, haci\u00e9ndolos piezas atemporales codiciadas por cualquier mujer elegante.<\/p>\n\n\n\n<p>Ya sea que visites la boutique Erica Maree en Hidalgo 167 en el centro de Puerto Vallarta o compres en l\u00ednea en www.ericamaree.com, seguramente encontrar\u00e1s una pieza que capture la esencia de la artesan\u00eda y el estilo mexicano.<\/p>\n\n\n\n<p>Para obtener m\u00e1s consejos de vacaciones de lujo en Puerto Vallarta, visita Pinnacle Resorts.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ubicado en el coraz\u00f3n de la Zona Rom\u00e1ntica de Puerto Vallarta, Pinnacle Resorts ofrece a sus hu\u00e9spedes f\u00e1cil acceso a algunas de las mejores tiendas de la zona. Una recomendaci\u00f3n destacada para los viajeros amantes de la moda es visitar la boutique Erica Maree. La fundadora y dise\u00f1adora Erica Black, originaria de Portland, Oreg\u00f3n y &#8230;<\/p>\n","protected":false},"author":1,"featured_media":7031,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_locale":"es_MX","_original_post":"https:\/\/pinnacleresortspv.com\/?p=7030","loftocean_post_format_gallery":"","loftocean_post_format_gallery_ids":"","loftocean_post_format_gallery_urls":"","loftocean_post_format_video_id":0,"loftocean_post_format_video_url":"","loftocean_post_format_video_type":"","loftocean_post_format_video":"","loftocean_post_format_audio_type":"","loftocean_post_format_audio_url":"","loftocean_post_format_audio_id":0,"loftocean_post_format_audio":"","loftocean-like-count":0,"cozystay_single_post_hide_site_header":"","cozystay_single_post_site_header_source":"","cozystay_single_post_custom_site_header":"0","cozystay_single_post_custom_sticky_site_header":"0","cozystay_single_post_hide_page_title":"","cozystay_single_post_site_footer_hide_main":"","cozystay_single_custom_site_footer_main_source":"","cozystay_single_custom_site_footer_main":"0","cozystay_single_post_site_footer_hide_above":"","cozystay_single_custom_site_footer_above_source":"","cozystay_single_custom_site_footer_above":"0","cozystay_single_post_site_footer_hide_instagram":"","cozystay_single_post_site_footer_hide_bottom":"","cozystay_single_custom_mobile_menu_source":"","cozystay_single_custom_mobile_menu":"0","cozystay_single_custom_mobile_menu_animation":"","cozystay_single_custom_mobile_menu_width":"","cozystay_single_custom_mobile_menu_custom_width":375,"cozystay_single_post_template":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-7033","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","es-MX"],"loftoceanMetas":{"authorName":"admin","categories":[{"name":"News","link":"https:\/\/pinnacleresortspv.com\/es\/blog\/category\/news\/","count":1384}],"date":"mayo 8, 2023","featuredImageSRC":"https:\/\/pinnacleresortspv.com\/wp-content\/uploads\/2025\/05\/post_148_imagenPortada-2-150x150.jpg"},"_links":{"self":[{"href":"https:\/\/pinnacleresortspv.com\/wp-json\/wp\/v2\/posts\/7033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pinnacleresortspv.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pinnacleresortspv.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pinnacleresortspv.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pinnacleresortspv.com\/wp-json\/wp\/v2\/comments?post=7033"}],"version-history":[{"count":1,"href":"https:\/\/pinnacleresortspv.com\/wp-json\/wp\/v2\/posts\/7033\/revisions"}],"predecessor-version":[{"id":7034,"href":"https:\/\/pinnacleresortspv.com\/wp-json\/wp\/v2\/posts\/7033\/revisions\/7034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pinnacleresortspv.com\/wp-json\/wp\/v2\/media\/7031"}],"wp:attachment":[{"href":"https:\/\/pinnacleresortspv.com\/wp-json\/wp\/v2\/media?parent=7033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pinnacleresortspv.com\/wp-json\/wp\/v2\/categories?post=7033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pinnacleresortspv.com\/wp-json\/wp\/v2\/tags?post=7033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}